{"id":6684,"date":"2025-04-23T05:58:31","date_gmt":"2025-04-23T03:58:31","guid":{"rendered":"https:\/\/eichenberger.staging2.net\/?page_id=6684"},"modified":"2025-04-23T06:30:17","modified_gmt":"2025-04-23T04:30:17","slug":"referenzen","status":"publish","type":"page","link":"https:\/\/www.eichenberger.com\/de\/referenzen\/","title":{"rendered":"Referenzen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6684\" class=\"elementor elementor-6684\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc02045 e-flex e-con-boxed e-con e-parent\" data-id=\"bc02045\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/vz-dca124e0-714.b-cdn.net\\\/fcf8bcd0-751a-4a58-9739-cd8a3a03aa9e\\\/play_480p.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t<div class=\"elementor-element elementor-element-59c1b45 elementor-widget elementor-widget-heading\" data-id=\"59c1b45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Eichenberger Referenzen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33518bf elementor-widget elementor-widget-heading\" data-id=\"33518bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Das bewegt unsere Kunden und Partner zur langj\u00e4hrigen Zusammenarbeit<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af513e6 elementor-widget elementor-widget-button\" data-id=\"af513e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Kontakt aufnehmen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-316c738 e-flex e-con-boxed e-con e-parent\" data-id=\"316c738\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aaa326a elementor-widget elementor-widget-heading\" data-id=\"aaa326a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Verauensvolle Zusammenarbeit mit gro\u00dfen Erfolgen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f9a9b1 elementor-widget elementor-widget-text-editor\" data-id=\"9f9a9b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Erfahren Sie hier wieso auch Sie mit uns zusammenarbeiten sollten und profitieren Sie wie auch andere Unternehmen von unseren Spezialisten im Gewinderollen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03cc5b0 e-flex e-con-boxed e-con e-parent\" data-id=\"03cc5b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd3af94 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"dd3af94\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:6714,&quot;masonry&quot;:&quot;yes&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:24,&quot;sizes&quot;:[]},&quot;_skin&quot;:&quot;post&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-6714\">.elementor-6714 .elementor-element.elementor-element-d0e2069{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--gap:0px 0px;--row-gap:0px;--column-gap:0px;--border-radius:5px 5px 5px 5px;--padding-top:40px;--padding-bottom:40px;--padding-left:40px;--padding-right:40px;}.elementor-6714 .elementor-element.elementor-element-d0e2069:not(.elementor-motion-effects-element-type-background), .elementor-6714 .elementor-element.elementor-element-d0e2069 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:var( --e-global-color-5ecb54b );}.elementor-widget-heading .elementor-heading-title{font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-6714 .elementor-element.elementor-element-de66006{text-align:start;}.elementor-6714 .elementor-element.elementor-element-de66006 .elementor-heading-title{font-size:16px;line-height:2em;color:var( --e-global-color-text );}.elementor-6714 .elementor-element.elementor-element-b1c4938{text-align:start;}.elementor-6714 .elementor-element.elementor-element-b1c4938 .elementor-heading-title{font-size:16px;font-weight:400;line-height:1.6em;-webkit-text-stroke-color:#000;stroke:#000;color:var( --e-global-color-text );}.elementor-6714 .elementor-element.elementor-element-f43313b{--spacer-size:24px;}.elementor-widget-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );}.elementor-6714 .elementor-element.elementor-element-d29ddfb img{width:200px;border-radius:5px 5px 5px 5px;}.elementor-6714 .elementor-element.elementor-element-d29ddfb{margin:0px 0px calc(var(--kit-widget-spacing, 0px) + 8px) 0px;}.elementor-6714 .elementor-element.elementor-element-3f03aa5 img{width:200px;border-radius:5px 5px 5px 5px;}.elementor-6714 .elementor-element.elementor-element-45a4563{--spacer-size:24px;}.elementor-widget-text-editor{font-family:var( --e-global-typography-text-font-family ), sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );color:var( --e-global-color-text );}.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:var( --e-global-color-primary );}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap, .elementor-widget-text-editor.elementor-drop-cap-view-default .elementor-drop-cap{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-6714 .elementor-element.elementor-element-4e641ac{font-family:var( --e-global-typography-text-font-family ), sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );color:var( --e-global-color-text );}@media(max-width:1360px){.elementor-widget-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-text-editor{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-6714 .elementor-element.elementor-element-4e641ac{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}}@media(max-width:1024px){.elementor-widget-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-text-editor{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-6714 .elementor-element.elementor-element-4e641ac{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}}@media(max-width:767px){.elementor-6714 .elementor-element.elementor-element-de66006{text-align:center;}.elementor-6714 .elementor-element.elementor-element-b1c4938{text-align:center;}.elementor-widget-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-text-editor{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-6714 .elementor-element.elementor-element-4e641ac{text-align:center;font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-6003 post-6003 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Daniel Klingler<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Gesch\u00e4ftsf\u00fchrer - Line Tech AG<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"400\" height=\"28\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Logo-1-LineTech.webp?strip=all\" class=\"attachment-large size-large wp-image-6007\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Logo-1-LineTech.webp?strip=all 400w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Logo-1-LineTech.webp?strip=all&amp;w=80 80w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Logo-1-LineTech.webp?strip=all&amp;w=160 160w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Logo-1-LineTech.webp?strip=all&amp;w=240 240w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Logo-1-LineTech.webp?strip=all&amp;w=320 320w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f03aa5 elementor-widget elementor-widget-image\" data-id=\"3f03aa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" fetchpriority=\"high\" decoding=\"async\" width=\"265\" height=\"247\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Line-Tech_-Daniel-Klingler-1-1-1.webp?strip=all\" class=\"attachment-large size-large wp-image-6006\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Line-Tech_-Daniel-Klingler-1-1-1.webp?strip=all 265w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Line-Tech_-Daniel-Klingler-1-1-1.webp?strip=all&amp;w=53 53w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Line-Tech_-Daniel-Klingler-1-1-1.webp?strip=all&amp;w=106 106w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Line-Tech_-Daniel-Klingler-1-1-1.webp?strip=all&amp;w=159 159w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Line-Tech_-Daniel-Klingler-1-1-1.webp?strip=all&amp;w=212 212w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tWir produzieren Linearachsen f\u00fcr die Automatisierung in der ganzen Welt. Bei unseren Antrieben mit Kugelgewindetrieben kommen wir an der Firma Eichenberger nicht vorbei. Insbesondere wenn es um Wirtschaftlichkeit bei mittleren und h\u00f6heren St\u00fcckzahlen geht! Bei der Anwendung im Textilbereich setzen wir eine von Eichenberger speziell entwickelte Spindel mit Durchmesser\/Steigungsverh\u00e4ltnis 25&#215;30 ein. Spezialt\u00e4ten heben uns und die Firma Eichenberger vom Wettbewerb ab und sichern uns den Erfolg! Wir sch\u00e4tzen den partnerschaftlichen und zielgerichteten Umgang vom Projektanfang bis zur Serienproduktion. Auch in schwierigen Situationen sucht man aktiv und fair nach L\u00f6sungen zur Zufriedenheit Aller. Wir werden jederzeit weitere Projekte mit der Firma Eichenberger angehen.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-6000 post-6000 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Mark Moore<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Managing Director - Moore International Ltd<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"227\" height=\"75\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-moore-1.png?strip=all\" class=\"attachment-large size-large wp-image-3816\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-moore-1.png?strip=all 227w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-moore-1.png?strip=all&amp;w=68 68w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-moore-1.png?strip=all&amp;w=136 136w\" sizes=\"(max-width: 227px) 100vw, 227px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f03aa5 elementor-widget elementor-widget-image\" data-id=\"3f03aa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Mark-Moore-Moore-International-UK.webp?strip=all&amp;t=1788381563\" class=\"attachment-large size-large wp-image-6888\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Mark-Moore-Moore-International-UK.webp?strip=all 400w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Mark-Moore-Moore-International-UK.webp?strip=all&amp;w=80 80w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Mark-Moore-Moore-International-UK.webp?strip=all&amp;w=160 160w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Mark-Moore-Moore-International-UK.webp?strip=all&amp;w=240 240w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Mark-Moore-Moore-International-UK.webp?strip=all&amp;w=320 320w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tEichenberger ist seit 23 Jahren einer unserer besten Lieferanten, und ich kann ehrlich sagen, dass es eine Freude war, zusammenzuarbeiten. Eichenberger bietet einen ausgezeichneten Service und hat innovative Ideen und L\u00f6sungen f\u00fcr Kundenprojekte. Wirklich hervorragend, und ich freue mich auf die n\u00e4chsten 23 Jahre.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5998 post-5998 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Iulian Boruz<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Team Leader Purchasing - Hamilton Central Europe SRL<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"75\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/38a59c8328cbfa56c8eb6bf46fc5ffd6.webp?strip=all\" class=\"attachment-large size-large wp-image-6902\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/38a59c8328cbfa56c8eb6bf46fc5ffd6.webp?strip=all 400w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/38a59c8328cbfa56c8eb6bf46fc5ffd6.webp?strip=all&amp;w=80 80w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/38a59c8328cbfa56c8eb6bf46fc5ffd6.webp?strip=all&amp;w=160 160w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/38a59c8328cbfa56c8eb6bf46fc5ffd6.webp?strip=all&amp;w=240 240w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/38a59c8328cbfa56c8eb6bf46fc5ffd6.webp?strip=all&amp;w=320 320w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tHamilton ZEUS basiert auf der revolution\u00e4ren Luftverdr\u00e4ngungspipettier-Technologie von Hamilton und wurde so konzipiert, dass es den gesamten Pipettiervorgang \u00fcbernimmt. Die ZEUS-Produkte verf\u00fcgen \u00fcber eine integrierte Z- Achsen-Bewegung zur automatischen Aufnahme der Spitze sowie zur Erkennung und Verfolgung des Fl\u00fcssigkeitsniveaus w\u00e4hrend des Ansaug- und Dispensiervorgangs. F\u00fcr die Z-Achsen-Bewegung wird die Spindel von Eichenberger eingesetzt. Die Komponente von Eichenberger bietet ein spezielles Gewinde \u201eSpeedy&#8220;, das das Hamilton ZEUS-Produkt robuster macht und im Vergleich zu Konkurrenzprodukten eine Hochgeschwindigkeitsbewegung erm\u00f6glicht. Die Zusammenarbeit mit Eichenberger ist sehr gut, wir haben immer rechtzeitig die Antworten und gute L\u00f6sungen f\u00fcr unsere Anwendung. Die Artikel werden nach unseren Bed\u00fcrfnissen personalisiert.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5996 post-5996 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Thomas Corthay<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Vizepr\u00e4sident - BIAR S.A.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"147\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-biar.webp?strip=all&amp;t=1788381563\" class=\"attachment-large size-large wp-image-4649\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-biar.webp?strip=all 400w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-biar.webp?strip=all&amp;w=80 80w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-biar.webp?strip=all&amp;w=160 160w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-biar.webp?strip=all&amp;w=240 240w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-biar.webp?strip=all&amp;w=320 320w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tBIAR SA bietet seit mehr als 35 Jahren Probenahmesysteme fi sehr anspruchsvolle Umgebungen, wie chemische, petrochemische und pharmazeutische Industrie, an. Alle Probenehmer werden am Schweizer Standort in Sembrancher entwickelt und hergestellt. Dank Eichenberger konnten wir eir effizienten Aktuator entwickeln, der einfach zu montieren ist u innerhalb des Projektbudgets bleibt. Wir arbeiten seit rund 15 Jahren mit Eichenberger zusammen Gem\u00e4ss unseren Spezifikationen fertigte Eichenberger einen Kugelk\u00e4fig aus rostfreiem Stahl, den wir seitdem f\u00fcr einen Gro\u00dfteil unserer Systeme verwenden. Der Spezialist garantier die optimale Qualit\u00e4t, die f\u00fcr die Probenahmesysteme unerl\u00e4sslich ist. In all den Jahren gab es nie ein Problem. Eichenberger bietet die Flexibilit\u00e4t, Lieferungen bei Bedarf vorzuziehen. Zudem erm\u00f6glicht uns Eichenbergers Kenntnis unseres Gesch\u00e4fts und unserer Anforderungen, L\u00f6sungen f\u00fcr eventuell auftretende Probleme zu finden.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5994 post-5994 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Vassil Shishkov<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">ABB Strategic buyer - Hitachi ABB Power Grids<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"25\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-hitachi-abb-1.jpg?strip=all\" class=\"attachment-large size-large wp-image-3791\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-hitachi-abb-1.jpg?strip=all 259w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-hitachi-abb-1.jpg?strip=all&amp;w=51 51w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-hitachi-abb-1.jpg?strip=all&amp;w=103 103w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-hitachi-abb-1.jpg?strip=all&amp;w=155 155w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-hitachi-abb-1.jpg?strip=all&amp;w=207 207w\" sizes=\"(max-width: 259px) 100vw, 259px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f03aa5 elementor-widget elementor-widget-image\" data-id=\"3f03aa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"206\" height=\"206\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Vassil-Shishkow-ABB-Bulgaria.webp?strip=all\" class=\"attachment-large size-large wp-image-6890\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Vassil-Shishkow-ABB-Bulgaria.webp?strip=all 206w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Vassil-Shishkow-ABB-Bulgaria-150x150.webp?strip=all 150w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Vassil-Shishkow-ABB-Bulgaria.webp?strip=all&amp;w=61 61w\" sizes=\"(max-width: 206px) 100vw, 206px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tABB ist ein Unternehmen mit einem der besten Lieferkettensysteme der Welt. Wir arbeiten mit qualifizierten und bevorzugten Lieferanten in unserer Lieferantendatenbank zusammen. Von unseren Lieferanten erwarten wir 100 % p\u00fcnktliche und 100 % qualit\u00e4tsgerechte Lieferung. Eichenberger geht auf diese Anforderungen ein und ist bereit, unerwartete Umst\u00e4nde pro-aktiv zu l\u00f6sen, was ihn zum besten Partner macht, den wir haben k\u00f6nnen. In professioneller Hinsicht k\u00f6nnen wir betonen, dass Eichenberger der beste Lieferant in Bezug auf Qualit\u00e4t und p\u00fcnktliche Lieferungen in der Produktkategorie Kugelgewindetriebe ist.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5990 post-5990 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Martina Klein<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Stv. Chefredakteurin Fachzeitschrift - Der Konstrukteur<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Der-konstrukteur.webp?strip=all\" class=\"attachment-large size-large wp-image-5992\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Der-konstrukteur.webp?strip=all 400w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Der-konstrukteur-150x150.webp?strip=all 150w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Der-konstrukteur.webp?strip=all&amp;w=80 80w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Der-konstrukteur.webp?strip=all&amp;w=200 200w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Der-konstrukteur.webp?strip=all&amp;w=280 280w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f03aa5 elementor-widget elementor-widget-image\" data-id=\"3f03aa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"266\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Martina-Klein.webp?strip=all\" class=\"attachment-large size-large wp-image-5991\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Martina-Klein.webp?strip=all 400w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Martina-Klein.webp?strip=all&amp;w=80 80w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Martina-Klein.webp?strip=all&amp;w=160 160w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Martina-Klein.webp?strip=all&amp;w=240 240w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Martina-Klein.webp?strip=all&amp;w=320 320w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\u201eKleine Helden im Alltag&#8220;. Aussergew\u00f6hnliche Projekte sind f\u00fcr die Entwickler bei Eichenberger eine willkommene Herausforderung. Gesucht waren Antriebselemente, die menschliche Finger bewegen &#8211; auf kleinstem Raum, schnell, pr\u00e4zise, dynamisch, leise, sicher und zuverl\u00e4ssig. Eichenberger hat den Handschuh aufgenommen, sich auf den Kunden und die Anwendung eingelassen. Und der Gewindespezialist hat gemeinsam mit dem schwedischen Exoskelett-Spezialisten im l\u00f6sungsorientierten Dialog eine passende Antwort gefunden, in Form von filigranen, kaltgerollten und induktiv geh\u00e4rteten Gewindespindeln. So werden die mechanischen Antriebs- elemente zu kleinen Helden, die den menschlichen Alltag erleichtern.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5988 post-5988 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Fabio Di Stefano<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Einkauf Mechanische Komponenten - Heidelberg Postpress Deutschland GmbH<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"215\" height=\"37\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Logo-Heidelberg.webp?strip=all\" class=\"attachment-large size-large wp-image-6891\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Logo-Heidelberg.webp?strip=all 215w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Logo-Heidelberg.webp?strip=all&amp;w=64 64w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Logo-Heidelberg.webp?strip=all&amp;w=129 129w\" sizes=\"(max-width: 215px) 100vw, 215px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDie Eichenberger Spindeln gehen bei uns direkt in das Herzst\u00fcck unserer Falzmaschinen ein, sie sorgen f\u00fcr die automatisierte Positionierung von Falzanschl\u00e4gen. Durch die gute Qualit\u00e4t der Spindeln konnten wir f\u00fcr den Endkunden unserer Maschinen hohe Prozesssicherheit gew\u00e4hrleisten. Qualit\u00e4tsm\u00e4ngel sind so gut wie ausgeschlossen und der Kunde bekommt ein langlebiges Produkt. Wir unterhalten eine konstante partnerschaftliche Gesch\u00e4ftsbeziehung mit Eichenberger. Stets kompetente Ansprechpartner im Vertrieb, der Technischen Abkl\u00e4rung und der Auftragsabwicklung, hohe Qualit\u00e4t zu vertretbaren Konditionen und ausnahmslose Termintreue zeichnen die Zusammenarbeit mit Eichenberger aus. Auch im Vergleich zu Mitbewerbern.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5986 post-5986 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Vera Wang<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Sales &amp; Marketing - Active Automatic Int'l Enterprise Co., Lt<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDer Einsatz von Eichenberger Produkten in linearen Aktuatoren verbessert unsere Wettbewerbsf\u00e4higkeit und die Kundenbindung erheblich. Durch das vielf\u00e4ltige Eichenberger Sortiment k\u00f6nnen wir je nach Kundenbed\u00fcrfnis die ideal geeignete Anpassung von Motor und Spindel vornehmen. Gleichbleibende Qualit\u00e4t bei maximaler Leistungsf\u00e4higkeit, h\u00f6chste Flexibilit\u00e4t f\u00fcr kundenspezifische Anpassungen, exzellente Serienfertigung: Das sind die Hauptgr\u00fcnde f\u00fcr die Zusammenarbeit mit Eichenberger, die angenehm und entspannt ist. Die Reaktionszeit ist kurz und die Kommunikation in allen Aspekten professionell, besonders auch in der gemeinsamen Kommunikation mit Endkunden. In Zeiten weltweit hoher Nachfrage konnten viele Lieferanten nicht liefern. Eichenberger jedoch konnte nach wie vor grosse Bestellmengen bew\u00e4ltigen und hat die Lieferzeiten sogar verk\u00fcrzt. Um den Bed\u00fcrfnissen der Kunden gerecht zu werden, ist Eichenberger der stabilste Partner.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5984 post-5984 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Cristina Torba<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">CEO und Mitinhaberin - Impex Tecniche Lineari Srl \/ MOVITEC<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"301\" height=\"156\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-impex-tecniche-lineari.webp?strip=all\" class=\"attachment-large size-large wp-image-4643\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-impex-tecniche-lineari.webp?strip=all 301w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-impex-tecniche-lineari.webp?strip=all&amp;w=60 60w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-impex-tecniche-lineari.webp?strip=all&amp;w=120 120w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-impex-tecniche-lineari.webp?strip=all&amp;w=180 180w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-impex-tecniche-lineari.webp?strip=all&amp;w=240 240w\" sizes=\"(max-width: 301px) 100vw, 301px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tWir verkaufen seit Ende der 80er Jahre Eichenberger Produkte. Die erste Mutter f\u00fcr die Carry Kugelgewindetriebe wurde von meinem Vater, Alvaro Torba, und Kurt Husistein gemeinsam entwickelt. Seither sind wir Zeugen des technologischen Wachstums und der Transformation: von einem kleinen Familienbetrieb zu einem grossen und erfolgreichen internationalen Unternehmen. Mit Unterst\u00fctzung der Eichenberger AG haben wir viele Projekte entwickelt &#8211; f\u00fcr Kunden, die uns \u00fcber Jahre bis heute treu geblieben sind. Grund hierf\u00fcr ist die jederzeit hoch spezialisierte technische und kaufm\u00e4nnische Unterst\u00fctzung aller Mitarbeitenden. Die hohe Wertsch\u00e4tzung der Partnerschaft ist bis heute eine fantastische Hilfe f\u00fcr uns alle. Wir sind sehr stolz, immer noch Teil des EAG-Gesch\u00e4fts zu sein! Vielen Dank von allen Impex-Mitarbeitern.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5981 post-5981 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Anton Moerkerken<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">DGA - A&amp;A Motion and Control BV<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f03aa5 elementor-widget elementor-widget-image\" data-id=\"3f03aa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"195\" height=\"306\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/AA-Anton-Moerkerken-1-1.jpg?strip=all\" class=\"attachment-large size-large wp-image-5982\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/AA-Anton-Moerkerken-1-1.jpg?strip=all 195w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/AA-Anton-Moerkerken-1-1.jpg?strip=all&amp;w=58 58w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/AA-Anton-Moerkerken-1-1.jpg?strip=all&amp;w=117 117w\" sizes=\"(max-width: 195px) 100vw, 195px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAls offizieller Wiederverk\u00e4ufer der Eichenberger Gewinde AG sch\u00e4tzen wir die Unterst\u00fctzung des Teams in Burg sehr. K\u00fcrzlich standen wir im Rahmen einer neuen Maschinenentwicklung vor einer Herausforderung: Der OEM wollte eine High Performance L\u00f6sung zu einem wettbewerbsf\u00e4higen Preis. Gemeinsam mit Eichenberger entwickelten wir eine massgeschneiderte Hochleistungsl\u00f6sung &#8211; einfach zu montieren und &#8222;mehr als nur eine Spindel&#8220;. Basierend auf dem Jahresbedarf analysierte Eichenberger die gesamte Lieferkette und eruierte, wie sich die Gesamtkosten senken lassen. Schliesslich erhielt der Kunde die richtige L\u00f6sung, Hochleistungsspindeln mit einfacher Montage, optimierter Lieferung und lokalem Support &#8211; zum richtigen Preis. Das ist es, was Partnerschaft ausmacht.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5978 post-5978 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Adrian Steiner<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">CEO - Thermoplan AG<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"45\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/LP-partner-thermoplan-1.png?strip=all\" class=\"attachment-large size-large wp-image-3811\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/LP-partner-thermoplan-1.png?strip=all 229w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/LP-partner-thermoplan-1.png?strip=all&amp;w=68 68w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/LP-partner-thermoplan-1.png?strip=all&amp;w=137 137w\" sizes=\"(max-width: 229px) 100vw, 229px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f03aa5 elementor-widget elementor-widget-image\" data-id=\"3f03aa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Adrian-Steiner-Thermoplan-167-2.webp?strip=all\" class=\"attachment-large size-large wp-image-6892\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Adrian-Steiner-Thermoplan-167-2.webp?strip=all 400w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Adrian-Steiner-Thermoplan-167-2-150x150.webp?strip=all 150w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Adrian-Steiner-Thermoplan-167-2.webp?strip=all&amp;w=80 80w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Adrian-Steiner-Thermoplan-167-2.webp?strip=all&amp;w=200 200w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Adrian-Steiner-Thermoplan-167-2.webp?strip=all&amp;w=280 280w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDie Produkte von Eichenberger AG finden seit Jahrzehnten Anwendung in einer Grosszahl von Thermoplan Kaffeemaschinen. Gemeinsam haben wir ein ausgekl\u00fcgeltes System entwickelt, das \u00fcber das theoretisch Machbare hinaus geht. In enger Zusammenarbeit verbessern wir die Produkte mit dem Know-how aller Beteiligten laufend weiter zugunsten der technischen Zuverl\u00e4ssigkeit.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5976 post-5976 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Shawn Hakim<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">echanical Engineering Manager - Motion Solutions<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"269\" height=\"59\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-motion-solutions.webp?strip=all&amp;t=1788381563\" class=\"attachment-large size-large wp-image-4642\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-motion-solutions.webp?strip=all 269w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-motion-solutions.webp?strip=all&amp;w=53 53w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-motion-solutions.webp?strip=all&amp;w=107 107w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-motion-solutions.webp?strip=all&amp;w=161 161w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-motion-solutions.webp?strip=all&amp;w=215 215w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f03aa5 elementor-widget elementor-widget-image\" data-id=\"3f03aa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"140\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Shawn-Hakim.jpg?strip=all&fit=140%2C140\" class=\"attachment-large size-large wp-image-3703\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tWir setzen Eichenberger-Produkte bei vielen verschiedenen Anwendungen ein. Die hohe Qualit\u00e4t, der niedrige Preis und der Kundenservice haben unsere Produkte zum Erfolg gebracht. Mit Hilfe von Eichenberger sind wir in der Lage, unsere Produktleistung durch sehr wirtschaftliche L\u00f6sungen zu verbessern. Damit erm\u00f6glichen wir es unseren Kunden, neue technologische Niveaus zu einem erschwinglichen Preis zu erreichen.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5971 post-5971 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Paul Harrison<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Senior Buyer - Varian Medical Systems (VAR) aus Palo Alto, Kalifornien, USA<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"156\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Varian_company_logo_2017.webp?strip=all\" class=\"attachment-large size-large wp-image-5972\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Varian_company_logo_2017.webp?strip=all 400w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Varian_company_logo_2017.webp?strip=all&amp;w=80 80w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Varian_company_logo_2017.webp?strip=all&amp;w=160 160w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Varian_company_logo_2017.webp?strip=all&amp;w=240 240w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/Varian_company_logo_2017.webp?strip=all&amp;w=320 320w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tEichenberger Produkte sind ein integraler Bestandteil unserer Hardware-Systeme f\u00fcr die Krebsbehandlung. Genauigkeit ist entscheidend, die Kugelgewindetriebe haben sich hier bew\u00e4hrt. Eichenberger hat unsere Volumenanforderungen erf\u00fcllt, unter den Bedingungen der Vorlaufzeit. Dies hat uns geholfen, auf Kundenw\u00fcnsche flexibel reagieren zu k\u00f6nnen. Eichenberger unterscheidet sich von anderen Anbietern durch sein Spezialwissen und sein ausgepr\u00e4gtes Verst\u00e4ndnis f\u00fcr unsere Anwendung. F\u00fcr Varian ist Eichenberger insgesamt ein sehr kompatibler Lieferant f\u00fcr die Medizinalbranche.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"6714\" class=\"elementor elementor-6714 e-loop-item e-loop-item-5968 post-5968 testimonial type-testimonial status-publish hentry referenz-typ-referenzen\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-d0e2069 e-flex e-con-boxed e-con e-parent\" data-id=\"d0e2069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de66006 elementor-widget elementor-widget-heading\" data-id=\"de66006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Marco Apolloni<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c4938 elementor-widget elementor-widget-heading\" data-id=\"b1c4938\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Team Lead Engineering Project Management - VAT Vakuumventile AG<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43313b elementor-widget elementor-widget-spacer\" data-id=\"f43313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29ddfb elementor-widget elementor-widget-image\" data-id=\"d29ddfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"301\" height=\"156\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-vat.webp?strip=all\" class=\"attachment-large size-large wp-image-4641\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-vat.webp?strip=all 301w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-vat.webp?strip=all&amp;w=60 60w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-vat.webp?strip=all&amp;w=120 120w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-vat.webp?strip=all&amp;w=180 180w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/eich-partner-vat.webp?strip=all&amp;w=240 240w\" sizes=\"(max-width: 301px) 100vw, 301px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f03aa5 elementor-widget elementor-widget-image\" data-id=\"3f03aa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"500\" src=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/VAT_Apolloni-Marco.webp?strip=all\" class=\"attachment-large size-large wp-image-5969\" alt=\"\" srcset=\"https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/VAT_Apolloni-Marco.webp?strip=all 400w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/VAT_Apolloni-Marco.webp?strip=all&amp;w=80 80w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/VAT_Apolloni-Marco.webp?strip=all&amp;w=160 160w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/VAT_Apolloni-Marco.webp?strip=all&amp;w=240 240w, https:\/\/e9rum28pkjh.exactdn.com\/wp-content\/uploads\/2025\/04\/VAT_Apolloni-Marco.webp?strip=all&amp;w=320 320w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a4563 elementor-widget elementor-widget-spacer\" data-id=\"45a4563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e641ac elementor-widget elementor-widget-text-editor\" data-id=\"4e641ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tZus\u00e4tzlich zu Vakuumventilen setzen wir Kugelgewindetriebe im Bereich \u00abMotion Components\u00bb ein. Dort kommen unsere Produkte in der Vakuumindustrie als Waferlifter, Ringlifter, Doorlifter, Shutterlifter etc. zur Anwendung. \r\nDie Optimierung auf den Bauraum und die optimale Integration in die Antriebseinheit mit Erf\u00fcllung aller Anforderungen an Pr\u00e4zision, Temperatur, Lebensdauer etc. haben bei uns hohe Wichtigkeit. Durch die sehr gute Kooperation mit Eichenberger und deren Pragmatismus und Kompetenz sind Prototypen entstanden, die zu wettbewerbsf\u00e4higen Produkten in der Halbleiterindustrie f\u00fchren.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Eichenberger Referenzen Das bewegt unsere Kunden und Partner zur langj\u00e4hrigen Zusammenarbeit Jetzt Kontakt aufnehmen Verauensvolle Zusammenarbeit mit gro\u00dfen Erfolgen Erfahren Sie hier wieso auch Sie mit uns zusammenarbeiten sollten und profitieren Sie wie auch andere Unternehmen von unseren Spezialisten im Gewinderollen.<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"element":[15,16,18,61],"seitenkategorie":[],"class_list":["post-6684","page","type-page","status-publish","hentry","element-blog","element-newsletter","element-fuer-sie-bewegen","element-zertifizierungen"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.eichenberger.com\/de\/wp-json\/wp\/v2\/pages\/6684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eichenberger.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eichenberger.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eichenberger.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eichenberger.com\/de\/wp-json\/wp\/v2\/comments?post=6684"}],"version-history":[{"count":0,"href":"https:\/\/www.eichenberger.com\/de\/wp-json\/wp\/v2\/pages\/6684\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eichenberger.com\/de\/wp-json\/wp\/v2\/media?parent=6684"}],"wp:term":[{"taxonomy":"element","embeddable":true,"href":"https:\/\/www.eichenberger.com\/de\/wp-json\/wp\/v2\/element?post=6684"},{"taxonomy":"seitenkategorie","embeddable":true,"href":"https:\/\/www.eichenberger.com\/de\/wp-json\/wp\/v2\/seitenkategorie?post=6684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}